{"id":98555,"date":"2026-08-20T19:25:43","date_gmt":"2026-08-20T17:25:43","guid":{"rendered":"https:\/\/autogroepdeschaetzen.be\/voertuigen\/ford-kuga-ecoboost-st-line-x-black-package\/"},"modified":"2026-09-01T14:13:39","modified_gmt":"2026-09-01T12:13:39","slug":"ford-kuga-ecoboost-st-line-x-black-package","status":"publish","type":"aw-vehicle","link":"https:\/\/autogroepdeschaetzen.be\/fr\/voertuigen\/ford-kuga-ecoboost-st-line-x-black-package\/","title":{"rendered":"Ford Kuga EcoBoost ST-Line X Black Package"},"content":{"rendered":"","protected":false},"template":"","class_list":["post-98555","aw-vehicle","type-aw-vehicle","status-publish","has-post-thumbnail","hentry","aw-brand-ford","aw-model-kuga","aw-transmission-manueel","aw-color-zilver","aw-emission-class-euro-6","aw-fuel-benzine","aw-bodytype-suv","aw-condition-tweedehands","aw_brand_model-kuga","aw-power-147","aw-max-speed-362"],"_links":{"self":[{"href":"https:\/\/autogroepdeschaetzen.be\/fr\/wp-json\/wp\/v2\/aw-vehicle\/98555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autogroepdeschaetzen.be\/fr\/wp-json\/wp\/v2\/aw-vehicle"}],"about":[{"href":"https:\/\/autogroepdeschaetzen.be\/fr\/wp-json\/wp\/v2\/types\/aw-vehicle"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autogroepdeschaetzen.be\/fr\/wp-json\/wp\/v2\/media\/98717"}],"wp:attachment":[{"href":"https:\/\/autogroepdeschaetzen.be\/fr\/wp-json\/wp\/v2\/media?parent=98555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}